{"id":7019,"date":"2018-05-05T19:55:44","date_gmt":"2018-05-05T19:55:44","guid":{"rendered":"https:\/\/teamstone.eu\/loja\/?post_type=product&#038;p=7019"},"modified":"2021-07-21T16:22:01","modified_gmt":"2021-07-21T16:22:01","slug":"camisa-de-dormir-comprida-branca-colibri-made-in-portugal-by-teamstone","status":"publish","type":"product","link":"https:\/\/teamstone.pt\/loja\/product\/camisa-de-dormir-comprida-branca-colibri-made-in-portugal-by-teamstone\/","title":{"rendered":"Camisa de dormir Colibri comprida, Branca"},"content":{"rendered":"<p>[vc_row content_placement=&#8221;top&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: left;\">Camisa T-shirt , comprida, em malha jersey muito confort\u00e1vel.<br \/>\nEnriquecida com serigrafia estampada , decote redondo com vivo verde \u00e1gua.<br \/>\nBase com acabamento em rolinho.<br \/>\nModelo desenhado para proporcionar bem estar e mobilidade<br \/>\nComprimento aprox. 110 cm<br \/>\nConfe\u00e7\u00e3o e controle de qualidade .<br \/>\nFabricado em Portugal<br \/>\nMade in Portugal<\/p>\n<p style=\"text-align: left;\">Composi\u00e7\u00e3o &amp; Cuidados:<br \/>\n\u2013 T\u00fanica em malha jersey<br \/>\n\u2013 Lav\u00e1vel na m\u00e1quina a 30\u00b0 com cores semelhantes.<br \/>\n\u2013 Lavar e passar a ferro do avesso.<br \/>\n\u2013 N\u00e3o secar na m\u00e1quina.<br \/>\n\u2013 Passar a ferro com temperatura baixa.<\/p>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h5 style=\"text-align: center;\"><span style=\"color: #ff6600;\">Campanha limitada ao stock existente.<\/span><\/h5>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h6><img loading=\"lazy\" class=\"alignnone wp-image-2914 size-full\" src=\"https:\/\/teamstone.eu\/loja\/wp-content\/uploads\/2017\/06\/reciclavel.png\" alt=\"\" width=\"50\" height=\"47\" \/><strong>Artigo recicl\u00e1vel; em final de \u201cvida\u201d pode ser colocado num ponto de recolha<\/strong>.<\/h6>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=&#8221;tamanhos&#8221;][vc_column][vc_empty_space height=&#8221;60px&#8221;][vc_tta_accordion style=&#8221;modern&#8221; active_section=&#8221;non-existing number&#8221; collapsible_all=&#8221;true&#8221;][vc_tta_section title=&#8221;CONSULTAR TABELA DE TAMANHOS&#8221; tab_id=&#8221;1524225399024-c7e87548-dfdd&#8221;][vc_column_text]<\/p>\n<div class=\"intro\">\n<p style=\"text-align: center;\">Medidas deste artigo<\/p>\n<p style=\"text-align: center;\">Todas as medidas s\u00e3o em cent\u00edmetros, com uma margem de 2\/3 cent\u00edmetros.<\/p>\n<\/div>\n<div class=\"guide\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Camisa T-shirt , comprida, em malha jersey muito confort\u00e1vel. Enriquecida com serigrafia estampada , decote redondo com vivo verde \u00e1gua. Base com acabamento em rolinho.<\/p>\n<h5><a href=\"#tamanhos\" rel=\"noopener\"><strong>CONSULTAR TABELA DE TAMANHOS<\/strong><\/a><\/h5>\n","protected":false},"featured_media":7048,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/teamstone.pt\/loja\/wp-json\/wp\/v2\/product\/7019"}],"collection":[{"href":"https:\/\/teamstone.pt\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teamstone.pt\/loja\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/teamstone.pt\/loja\/wp-json\/wp\/v2\/comments?post=7019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teamstone.pt\/loja\/wp-json\/wp\/v2\/media\/7048"}],"wp:attachment":[{"href":"https:\/\/teamstone.pt\/loja\/wp-json\/wp\/v2\/media?parent=7019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}